{"id":2589,"date":"2024-01-31T16:17:07","date_gmt":"2024-01-31T19:17:07","guid":{"rendered":"https:\/\/isohar.com\/?page_id=2589"},"modified":"2024-08-23T09:58:00","modified_gmt":"2024-08-23T12:58:00","slug":"galeria","status":"publish","type":"page","link":"https:\/\/isohar.com\/index.php\/galeria\/","title":{"rendered":"Galeria"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"2589\" class=\"elementor elementor-2589\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-945f2a1 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"945f2a1\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-a5be0f8\" data-id=\"a5be0f8\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-8be6caf elementor-widget elementor-widget-heading\" data-id=\"8be6caf\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Nuestras Instalaciones <\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-c73fe47 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"c73fe47\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-5ffb32e\" data-id=\"5ffb32e\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-a4a2b47 elementor-widget elementor-widget-spacer\" data-id=\"a4a2b47\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-85b7092 elementor-widget elementor-widget-pg-fabric\" data-id=\"85b7092\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"pg-fabric.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"pg-fabric-grid pg-grid pg-fabric-hover-effect-default\">\n\t\t\t\n\t\t<div class=\"pg-fabric-item pg-item elementor-repeater-item-7a2c164\">\n\t\t\t\t\t\t\t\t<div class=\"pg-fabric-image-wrap bdt-pg-img-mask\">\n\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"683\" height=\"1024\" src=\"https:\/\/isohar.com\/wp-content\/uploads\/2023\/08\/TALLER-HIDRAULICA-683x1024.jpg\" class=\"pg-fabric-img\" alt=\"\" srcset=\"https:\/\/isohar.com\/wp-content\/uploads\/2023\/08\/TALLER-HIDRAULICA-683x1024.jpg 683w, https:\/\/isohar.com\/wp-content\/uploads\/2023\/08\/TALLER-HIDRAULICA-200x300.jpg 200w, https:\/\/isohar.com\/wp-content\/uploads\/2023\/08\/TALLER-HIDRAULICA-768x1152.jpg 768w, https:\/\/isohar.com\/wp-content\/uploads\/2023\/08\/TALLER-HIDRAULICA-1024x1536.jpg 1024w, https:\/\/isohar.com\/wp-content\/uploads\/2023\/08\/TALLER-HIDRAULICA-1365x2048.jpg 1365w, https:\/\/isohar.com\/wp-content\/uploads\/2023\/08\/TALLER-HIDRAULICA-scaled.jpg 1707w\" sizes=\"(max-width: 683px) 100vw, 683px\" \/>\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"pg-fabric-content\">\n\t\t\t\t\t\t\t\t<div class=\"pg-fabric-inner-content\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\n\t\t\n\t\t<div class=\"pg-fabric-item pg-item elementor-repeater-item-b169489\">\n\t\t\t\t\t\t\t\t<div class=\"pg-fabric-image-wrap bdt-pg-img-mask\">\n\t\t\t<img decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/isohar.com\/wp-content\/uploads\/2024\/02\/ISOH-alta-calidad-18-1024x683.jpg\" class=\"pg-fabric-img\" alt=\"\" srcset=\"https:\/\/isohar.com\/wp-content\/uploads\/2024\/02\/ISOH-alta-calidad-18-1024x683.jpg 1024w, https:\/\/isohar.com\/wp-content\/uploads\/2024\/02\/ISOH-alta-calidad-18-300x200.jpg 300w, https:\/\/isohar.com\/wp-content\/uploads\/2024\/02\/ISOH-alta-calidad-18-768x512.jpg 768w, https:\/\/isohar.com\/wp-content\/uploads\/2024\/02\/ISOH-alta-calidad-18-1536x1024.jpg 1536w, https:\/\/isohar.com\/wp-content\/uploads\/2024\/02\/ISOH-alta-calidad-18-2048x1365.jpg 2048w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"pg-fabric-content\">\n\t\t\t\t\t\t\t\t<div class=\"pg-fabric-inner-content\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\n\t\t\n\t\t<div class=\"pg-fabric-item pg-item elementor-repeater-item-23acdbd\">\n\t\t\t\t\t\t\t\t<div class=\"pg-fabric-image-wrap bdt-pg-img-mask\">\n\t\t\t<img decoding=\"async\" width=\"950\" height=\"1024\" src=\"https:\/\/isohar.com\/wp-content\/uploads\/2024\/02\/IMG_20220608_171346_edited_edited-950x1024.jpg\" class=\"pg-fabric-img\" alt=\"\" srcset=\"https:\/\/isohar.com\/wp-content\/uploads\/2024\/02\/IMG_20220608_171346_edited_edited-950x1024.jpg 950w, https:\/\/isohar.com\/wp-content\/uploads\/2024\/02\/IMG_20220608_171346_edited_edited-278x300.jpg 278w, https:\/\/isohar.com\/wp-content\/uploads\/2024\/02\/IMG_20220608_171346_edited_edited-768x828.jpg 768w, https:\/\/isohar.com\/wp-content\/uploads\/2024\/02\/IMG_20220608_171346_edited_edited-1425x1536.jpg 1425w, https:\/\/isohar.com\/wp-content\/uploads\/2024\/02\/IMG_20220608_171346_edited_edited-1899x2048.jpg 1899w\" sizes=\"(max-width: 950px) 100vw, 950px\" \/>\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"pg-fabric-content\">\n\t\t\t\t\t\t\t\t<div class=\"pg-fabric-inner-content\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\n\t\t\n\t\t<div class=\"pg-fabric-item pg-item elementor-repeater-item-aefa007\">\n\t\t\t\t\t\t\t\t<div class=\"pg-fabric-image-wrap bdt-pg-img-mask\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/isohar.com\/wp-content\/uploads\/2024\/02\/ISOH-alta-calidad-16-1024x683.jpg\" class=\"pg-fabric-img\" alt=\"\" srcset=\"https:\/\/isohar.com\/wp-content\/uploads\/2024\/02\/ISOH-alta-calidad-16-1024x683.jpg 1024w, https:\/\/isohar.com\/wp-content\/uploads\/2024\/02\/ISOH-alta-calidad-16-300x200.jpg 300w, https:\/\/isohar.com\/wp-content\/uploads\/2024\/02\/ISOH-alta-calidad-16-768x512.jpg 768w, https:\/\/isohar.com\/wp-content\/uploads\/2024\/02\/ISOH-alta-calidad-16-1536x1024.jpg 1536w, https:\/\/isohar.com\/wp-content\/uploads\/2024\/02\/ISOH-alta-calidad-16-2048x1365.jpg 2048w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"pg-fabric-content\">\n\t\t\t\t\t\t\t\t<div class=\"pg-fabric-inner-content\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\n\t\t\n\t\t<div class=\"pg-fabric-item pg-item elementor-repeater-item-5c0beda\">\n\t\t\t\t\t\t\t\t<div class=\"pg-fabric-image-wrap bdt-pg-img-mask\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"662\" src=\"https:\/\/isohar.com\/wp-content\/uploads\/2023\/08\/WhatsApp-Image-2023-08-08-at-10.33.26-1024x662.jpeg\" class=\"pg-fabric-img\" alt=\"\" srcset=\"https:\/\/isohar.com\/wp-content\/uploads\/2023\/08\/WhatsApp-Image-2023-08-08-at-10.33.26-1024x662.jpeg 1024w, https:\/\/isohar.com\/wp-content\/uploads\/2023\/08\/WhatsApp-Image-2023-08-08-at-10.33.26-300x194.jpeg 300w, https:\/\/isohar.com\/wp-content\/uploads\/2023\/08\/WhatsApp-Image-2023-08-08-at-10.33.26-768x496.jpeg 768w, https:\/\/isohar.com\/wp-content\/uploads\/2023\/08\/WhatsApp-Image-2023-08-08-at-10.33.26.jpeg 1080w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"pg-fabric-content\">\n\t\t\t\t\t\t\t\t<div class=\"pg-fabric-inner-content\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\n\t\t\n\t\t<div class=\"pg-fabric-item pg-item elementor-repeater-item-b9362e9\">\n\t\t\t\t\t\t\t\t<div class=\"pg-fabric-image-wrap bdt-pg-img-mask\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"1024\" src=\"https:\/\/isohar.com\/wp-content\/uploads\/2024\/02\/IMG_20230111_132306_edited-768x1024.jpg\" class=\"pg-fabric-img\" alt=\"\" srcset=\"https:\/\/isohar.com\/wp-content\/uploads\/2024\/02\/IMG_20230111_132306_edited-768x1024.jpg 768w, https:\/\/isohar.com\/wp-content\/uploads\/2024\/02\/IMG_20230111_132306_edited-225x300.jpg 225w, https:\/\/isohar.com\/wp-content\/uploads\/2024\/02\/IMG_20230111_132306_edited-1152x1536.jpg 1152w, https:\/\/isohar.com\/wp-content\/uploads\/2024\/02\/IMG_20230111_132306_edited-1536x2048.jpg 1536w, https:\/\/isohar.com\/wp-content\/uploads\/2024\/02\/IMG_20230111_132306_edited.jpg 1588w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/>\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"pg-fabric-content\">\n\t\t\t\t\t\t\t\t<div class=\"pg-fabric-inner-content\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-d5f8856 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"d5f8856\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-4351164\" data-id=\"4351164\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-27eb2d6 elementor-widget elementor-widget-spacer\" data-id=\"27eb2d6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-72f5d15 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"72f5d15\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-44e33a0\" data-id=\"44e33a0\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2623d82 elementor-widget elementor-widget-heading\" data-id=\"2623d82\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Reparacion y Mantenimiento <\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-5e6429d elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"5e6429d\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-b3cb0c0\" data-id=\"b3cb0c0\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7da6932 elementor-widget elementor-widget-spacer\" data-id=\"7da6932\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-627059e elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"627059e\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-ca51699\" data-id=\"ca51699\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-a7f4781 elementor-widget elementor-widget-pg-fabric\" data-id=\"a7f4781\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"pg-fabric.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"pg-fabric-grid pg-grid pg-fabric-hover-effect-default\">\n\t\t\t\n\t\t<div class=\"pg-fabric-item pg-item elementor-repeater-item-4dd9844\">\n\t\t\t\t\t\t\t\t<div class=\"pg-fabric-image-wrap bdt-pg-img-mask\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"716\" height=\"879\" src=\"https:\/\/isohar.com\/wp-content\/uploads\/2024\/02\/WhatsApp-Image-2024-01-18-at-09.40.56.jpeg\" class=\"pg-fabric-img\" alt=\"\" srcset=\"https:\/\/isohar.com\/wp-content\/uploads\/2024\/02\/WhatsApp-Image-2024-01-18-at-09.40.56.jpeg 716w, https:\/\/isohar.com\/wp-content\/uploads\/2024\/02\/WhatsApp-Image-2024-01-18-at-09.40.56-244x300.jpeg 244w\" sizes=\"(max-width: 716px) 100vw, 716px\" \/>\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"pg-fabric-content\">\n\t\t\t\t\t\t\t\t<div class=\"pg-fabric-inner-content\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\n\t\t\n\t\t<div class=\"pg-fabric-item pg-item elementor-repeater-item-e502501\">\n\t\t\t\t\t\t\t\t<div class=\"pg-fabric-image-wrap bdt-pg-img-mask\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"805\" height=\"1024\" src=\"https:\/\/isohar.com\/wp-content\/uploads\/2024\/02\/IMG_20220512_115053-scaled-e1707940852481-805x1024.jpg\" class=\"pg-fabric-img\" alt=\"\" srcset=\"https:\/\/isohar.com\/wp-content\/uploads\/2024\/02\/IMG_20220512_115053-scaled-e1707940852481-805x1024.jpg 805w, https:\/\/isohar.com\/wp-content\/uploads\/2024\/02\/IMG_20220512_115053-scaled-e1707940852481-236x300.jpg 236w, https:\/\/isohar.com\/wp-content\/uploads\/2024\/02\/IMG_20220512_115053-scaled-e1707940852481-768x976.jpg 768w, https:\/\/isohar.com\/wp-content\/uploads\/2024\/02\/IMG_20220512_115053-scaled-e1707940852481-1208x1536.jpg 1208w, https:\/\/isohar.com\/wp-content\/uploads\/2024\/02\/IMG_20220512_115053-scaled-e1707940852481-1611x2048.jpg 1611w, https:\/\/isohar.com\/wp-content\/uploads\/2024\/02\/IMG_20220512_115053-scaled-e1707940852481.jpg 1913w\" sizes=\"(max-width: 805px) 100vw, 805px\" \/>\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"pg-fabric-content\">\n\t\t\t\t\t\t\t\t<div class=\"pg-fabric-inner-content\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\n\t\t\n\t\t<div class=\"pg-fabric-item pg-item elementor-repeater-item-d7fcfec\">\n\t\t\t\t\t\t\t\t<div class=\"pg-fabric-image-wrap bdt-pg-img-mask\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"716\" height=\"814\" src=\"https:\/\/isohar.com\/wp-content\/uploads\/2024\/02\/WhatsApp-Image-2024-01-18-at-09.40.57.jpeg\" class=\"pg-fabric-img\" alt=\"\" srcset=\"https:\/\/isohar.com\/wp-content\/uploads\/2024\/02\/WhatsApp-Image-2024-01-18-at-09.40.57.jpeg 716w, https:\/\/isohar.com\/wp-content\/uploads\/2024\/02\/WhatsApp-Image-2024-01-18-at-09.40.57-264x300.jpeg 264w\" sizes=\"(max-width: 716px) 100vw, 716px\" \/>\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"pg-fabric-content\">\n\t\t\t\t\t\t\t\t<div class=\"pg-fabric-inner-content\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\n\t\t\n\t\t<div class=\"pg-fabric-item pg-item elementor-repeater-item-a218bb9\">\n\t\t\t\t\t\t\t\t<div class=\"pg-fabric-image-wrap bdt-pg-img-mask\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"871\" height=\"1024\" src=\"https:\/\/isohar.com\/wp-content\/uploads\/2024\/01\/WhatsApp-Image-2024-01-16-at-11.24.24-1-871x1024.jpeg\" class=\"pg-fabric-img\" alt=\"\" srcset=\"https:\/\/isohar.com\/wp-content\/uploads\/2024\/01\/WhatsApp-Image-2024-01-16-at-11.24.24-1-871x1024.jpeg 871w, https:\/\/isohar.com\/wp-content\/uploads\/2024\/01\/WhatsApp-Image-2024-01-16-at-11.24.24-1-255x300.jpeg 255w, https:\/\/isohar.com\/wp-content\/uploads\/2024\/01\/WhatsApp-Image-2024-01-16-at-11.24.24-1-768x902.jpeg 768w, https:\/\/isohar.com\/wp-content\/uploads\/2024\/01\/WhatsApp-Image-2024-01-16-at-11.24.24-1.jpeg 1080w\" sizes=\"(max-width: 871px) 100vw, 871px\" \/>\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"pg-fabric-content\">\n\t\t\t\t\t\t\t\t<div class=\"pg-fabric-inner-content\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\n\t\t\n\t\t<div class=\"pg-fabric-item pg-item elementor-repeater-item-35b7ca8\">\n\t\t\t\t\t\t\t\t<div class=\"pg-fabric-image-wrap bdt-pg-img-mask\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"819\" height=\"1024\" src=\"https:\/\/isohar.com\/wp-content\/uploads\/2024\/02\/IMG_20220909_115833-scaled-e1708009697327-819x1024.jpg\" class=\"pg-fabric-img\" alt=\"\" srcset=\"https:\/\/isohar.com\/wp-content\/uploads\/2024\/02\/IMG_20220909_115833-scaled-e1708009697327-819x1024.jpg 819w, https:\/\/isohar.com\/wp-content\/uploads\/2024\/02\/IMG_20220909_115833-scaled-e1708009697327-240x300.jpg 240w, https:\/\/isohar.com\/wp-content\/uploads\/2024\/02\/IMG_20220909_115833-scaled-e1708009697327-768x961.jpg 768w, https:\/\/isohar.com\/wp-content\/uploads\/2024\/02\/IMG_20220909_115833-scaled-e1708009697327-1228x1536.jpg 1228w, https:\/\/isohar.com\/wp-content\/uploads\/2024\/02\/IMG_20220909_115833-scaled-e1708009697327-1637x2048.jpg 1637w, https:\/\/isohar.com\/wp-content\/uploads\/2024\/02\/IMG_20220909_115833-scaled-e1708009697327.jpg 1913w\" sizes=\"(max-width: 819px) 100vw, 819px\" \/>\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"pg-fabric-content\">\n\t\t\t\t\t\t\t\t<div class=\"pg-fabric-inner-content\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\n\t\t\n\t\t<div class=\"pg-fabric-item pg-item elementor-repeater-item-3b9fd95\">\n\t\t\t\t\t\t\t\t<div class=\"pg-fabric-image-wrap bdt-pg-img-mask\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"1024\" src=\"https:\/\/isohar.com\/wp-content\/uploads\/2024\/02\/IMG_20220730_183924_edited-768x1024.jpg\" class=\"pg-fabric-img\" alt=\"\" srcset=\"https:\/\/isohar.com\/wp-content\/uploads\/2024\/02\/IMG_20220730_183924_edited-768x1024.jpg 768w, https:\/\/isohar.com\/wp-content\/uploads\/2024\/02\/IMG_20220730_183924_edited-225x300.jpg 225w, https:\/\/isohar.com\/wp-content\/uploads\/2024\/02\/IMG_20220730_183924_edited-1152x1536.jpg 1152w, https:\/\/isohar.com\/wp-content\/uploads\/2024\/02\/IMG_20220730_183924_edited-1536x2048.jpg 1536w, https:\/\/isohar.com\/wp-content\/uploads\/2024\/02\/IMG_20220730_183924_edited-scaled.jpg 1920w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/>\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"pg-fabric-content\">\n\t\t\t\t\t\t\t\t<div class=\"pg-fabric-inner-content\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-70769bf elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"70769bf\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-f2de3a6\" data-id=\"f2de3a6\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-a7f3b39 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"a7f3b39\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-3c0737a\" data-id=\"3c0737a\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-56365f9 elementor-widget elementor-widget-heading\" data-id=\"56365f9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Torneria y Metalurgica <\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-616f0cd elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"616f0cd\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-2211485\" data-id=\"2211485\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-355b635 elementor-widget elementor-widget-spacer\" data-id=\"355b635\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-96d797a elementor-widget elementor-widget-pg-fabric\" data-id=\"96d797a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"pg-fabric.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"pg-fabric-grid pg-grid pg-fabric-hover-effect-default\">\n\t\t\t\n\t\t<div class=\"pg-fabric-item pg-item elementor-repeater-item-c0b5a2e\">\n\t\t\t\t\t\t\t\t<div class=\"pg-fabric-image-wrap bdt-pg-img-mask\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"658\" height=\"1024\" src=\"https:\/\/isohar.com\/wp-content\/uploads\/2024\/01\/METALUIRGICA-658x1024.jpeg\" class=\"pg-fabric-img\" alt=\"\" srcset=\"https:\/\/isohar.com\/wp-content\/uploads\/2024\/01\/METALUIRGICA-658x1024.jpeg 658w, https:\/\/isohar.com\/wp-content\/uploads\/2024\/01\/METALUIRGICA-193x300.jpeg 193w, https:\/\/isohar.com\/wp-content\/uploads\/2024\/01\/METALUIRGICA-768x1195.jpeg 768w, https:\/\/isohar.com\/wp-content\/uploads\/2024\/01\/METALUIRGICA.jpeg 900w\" sizes=\"(max-width: 658px) 100vw, 658px\" \/>\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"pg-fabric-content\">\n\t\t\t\t\t\t\t\t<div class=\"pg-fabric-inner-content\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\n\t\t\n\t\t<div class=\"pg-fabric-item pg-item elementor-repeater-item-ede9ef7\">\n\t\t\t\t\t\t\t\t<div class=\"pg-fabric-image-wrap bdt-pg-img-mask\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"809\" height=\"1024\" src=\"https:\/\/isohar.com\/wp-content\/uploads\/2024\/01\/IMG_20220802_085917-scaled-e1708012740737-809x1024.jpg\" class=\"pg-fabric-img\" alt=\"\" srcset=\"https:\/\/isohar.com\/wp-content\/uploads\/2024\/01\/IMG_20220802_085917-scaled-e1708012740737-809x1024.jpg 809w, https:\/\/isohar.com\/wp-content\/uploads\/2024\/01\/IMG_20220802_085917-scaled-e1708012740737-237x300.jpg 237w, https:\/\/isohar.com\/wp-content\/uploads\/2024\/01\/IMG_20220802_085917-scaled-e1708012740737-768x973.jpg 768w, https:\/\/isohar.com\/wp-content\/uploads\/2024\/01\/IMG_20220802_085917-scaled-e1708012740737-1213x1536.jpg 1213w, https:\/\/isohar.com\/wp-content\/uploads\/2024\/01\/IMG_20220802_085917-scaled-e1708012740737-1617x2048.jpg 1617w, https:\/\/isohar.com\/wp-content\/uploads\/2024\/01\/IMG_20220802_085917-scaled-e1708012740737.jpg 1900w\" sizes=\"(max-width: 809px) 100vw, 809px\" \/>\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"pg-fabric-content\">\n\t\t\t\t\t\t\t\t<div class=\"pg-fabric-inner-content\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\n\t\t\n\t\t<div class=\"pg-fabric-item pg-item elementor-repeater-item-39bdb22\">\n\t\t\t\t\t\t\t\t<div class=\"pg-fabric-image-wrap bdt-pg-img-mask\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"576\" src=\"https:\/\/isohar.com\/wp-content\/uploads\/2024\/01\/pjv123-1024x576.jpg\" class=\"pg-fabric-img\" alt=\"\" srcset=\"https:\/\/isohar.com\/wp-content\/uploads\/2024\/01\/pjv123-1024x576.jpg 1024w, https:\/\/isohar.com\/wp-content\/uploads\/2024\/01\/pjv123-300x169.jpg 300w, https:\/\/isohar.com\/wp-content\/uploads\/2024\/01\/pjv123-768x432.jpg 768w, https:\/\/isohar.com\/wp-content\/uploads\/2024\/01\/pjv123-820x461.jpg 820w, https:\/\/isohar.com\/wp-content\/uploads\/2024\/01\/pjv123-1170x658.jpg 1170w, https:\/\/isohar.com\/wp-content\/uploads\/2024\/01\/pjv123-177x100.jpg 177w, https:\/\/isohar.com\/wp-content\/uploads\/2024\/01\/pjv123.jpg 1280w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"pg-fabric-content\">\n\t\t\t\t\t\t\t\t<div class=\"pg-fabric-inner-content\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-3e02d75 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"3e02d75\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-730b006\" data-id=\"730b006\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-be99232 elementor-widget elementor-widget-image\" data-id=\"be99232\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"1024\" src=\"https:\/\/isohar.com\/wp-content\/uploads\/2024\/08\/Diseno-sin-titulo-3-1024x1024.jpg\" class=\"attachment-large size-large wp-image-2828\" alt=\"\" srcset=\"https:\/\/isohar.com\/wp-content\/uploads\/2024\/08\/Diseno-sin-titulo-3-1024x1024.jpg 1024w, https:\/\/isohar.com\/wp-content\/uploads\/2024\/08\/Diseno-sin-titulo-3-300x300.jpg 300w, https:\/\/isohar.com\/wp-content\/uploads\/2024\/08\/Diseno-sin-titulo-3-150x150.jpg 150w, https:\/\/isohar.com\/wp-content\/uploads\/2024\/08\/Diseno-sin-titulo-3-768x768.jpg 768w, https:\/\/isohar.com\/wp-content\/uploads\/2024\/08\/Diseno-sin-titulo-3.jpg 1080w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-faee1bf elementor-widget elementor-widget-spacer\" data-id=\"faee1bf\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-39f9eae elementor-widget elementor-widget-spacer\" data-id=\"39f9eae\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-bd38967 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"bd38967\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-7737040\" data-id=\"7737040\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-40496f1 elementor-widget elementor-widget-pg-fabric\" data-id=\"40496f1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"pg-fabric.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"pg-fabric-grid pg-grid pg-fabric-hover-effect-default\">\n\t\t\t\n\t\t<div class=\"pg-fabric-item pg-item elementor-repeater-item-b72fc10\">\n\t\t\t\t\t\t\t\t<div class=\"pg-fabric-image-wrap bdt-pg-img-mask\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"1024\" src=\"https:\/\/isohar.com\/wp-content\/uploads\/2024\/02\/imagen-principal-1-1-768x1024.jpg\" class=\"pg-fabric-img\" alt=\"\" srcset=\"https:\/\/isohar.com\/wp-content\/uploads\/2024\/02\/imagen-principal-1-1-768x1024.jpg 768w, https:\/\/isohar.com\/wp-content\/uploads\/2024\/02\/imagen-principal-1-1-225x300.jpg 225w, https:\/\/isohar.com\/wp-content\/uploads\/2024\/02\/imagen-principal-1-1-1152x1536.jpg 1152w, https:\/\/isohar.com\/wp-content\/uploads\/2024\/02\/imagen-principal-1-1-1536x2048.jpg 1536w, https:\/\/isohar.com\/wp-content\/uploads\/2024\/02\/imagen-principal-1-1-scaled.jpg 1920w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/>\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"pg-fabric-content\">\n\t\t\t\t\t\t\t\t<div class=\"pg-fabric-inner-content\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\n\t\t\n\t\t<div class=\"pg-fabric-item pg-item elementor-repeater-item-93c726c\">\n\t\t\t\t\t\t\t\t<div class=\"pg-fabric-image-wrap bdt-pg-img-mask\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"769\" height=\"1024\" src=\"https:\/\/isohar.com\/wp-content\/uploads\/2024\/02\/IMG_20220512_115132_edited-769x1024.jpg\" class=\"pg-fabric-img\" alt=\"\" srcset=\"https:\/\/isohar.com\/wp-content\/uploads\/2024\/02\/IMG_20220512_115132_edited-769x1024.jpg 769w, https:\/\/isohar.com\/wp-content\/uploads\/2024\/02\/IMG_20220512_115132_edited-225x300.jpg 225w, https:\/\/isohar.com\/wp-content\/uploads\/2024\/02\/IMG_20220512_115132_edited-768x1023.jpg 768w, https:\/\/isohar.com\/wp-content\/uploads\/2024\/02\/IMG_20220512_115132_edited-1154x1536.jpg 1154w, https:\/\/isohar.com\/wp-content\/uploads\/2024\/02\/IMG_20220512_115132_edited-1538x2048.jpg 1538w, https:\/\/isohar.com\/wp-content\/uploads\/2024\/02\/IMG_20220512_115132_edited-scaled.jpg 1923w\" sizes=\"(max-width: 769px) 100vw, 769px\" \/>\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"pg-fabric-content\">\n\t\t\t\t\t\t\t\t<div class=\"pg-fabric-inner-content\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\n\t\t\n\t\t<div class=\"pg-fabric-item pg-item elementor-repeater-item-d55735e\">\n\t\t\t\t\t\t\t\t<div class=\"pg-fabric-image-wrap bdt-pg-img-mask\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"839\" height=\"1024\" src=\"https:\/\/isohar.com\/wp-content\/uploads\/2024\/02\/WhatsApp-Image-2024-01-12-at-15.51.03-1-839x1024.jpeg\" class=\"pg-fabric-img\" alt=\"\" srcset=\"https:\/\/isohar.com\/wp-content\/uploads\/2024\/02\/WhatsApp-Image-2024-01-12-at-15.51.03-1-839x1024.jpeg 839w, https:\/\/isohar.com\/wp-content\/uploads\/2024\/02\/WhatsApp-Image-2024-01-12-at-15.51.03-1-246x300.jpeg 246w, https:\/\/isohar.com\/wp-content\/uploads\/2024\/02\/WhatsApp-Image-2024-01-12-at-15.51.03-1-768x937.jpeg 768w, https:\/\/isohar.com\/wp-content\/uploads\/2024\/02\/WhatsApp-Image-2024-01-12-at-15.51.03-1.jpeg 1080w\" sizes=\"(max-width: 839px) 100vw, 839px\" \/>\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"pg-fabric-content\">\n\t\t\t\t\t\t\t\t<div class=\"pg-fabric-inner-content\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-dd261a2 elementor-widget elementor-widget-pg-fabric\" data-id=\"dd261a2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"pg-fabric.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"pg-fabric-grid pg-grid pg-fabric-hover-effect-default\">\n\t\t\t\n\t\t<div class=\"pg-fabric-item pg-item elementor-repeater-item-04b49bc\">\n\t\t\t\t\t\t\t\t<div class=\"pg-fabric-image-wrap bdt-pg-img-mask\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"1024\" src=\"https:\/\/isohar.com\/wp-content\/uploads\/2024\/05\/WhatsApp-Image-2024-05-24-at-11.38.24-768x1024.jpeg\" class=\"pg-fabric-img\" alt=\"Comando de valvulas\" srcset=\"https:\/\/isohar.com\/wp-content\/uploads\/2024\/05\/WhatsApp-Image-2024-05-24-at-11.38.24-768x1024.jpeg 768w, https:\/\/isohar.com\/wp-content\/uploads\/2024\/05\/WhatsApp-Image-2024-05-24-at-11.38.24-225x300.jpeg 225w, https:\/\/isohar.com\/wp-content\/uploads\/2024\/05\/WhatsApp-Image-2024-05-24-at-11.38.24-1152x1536.jpeg 1152w, https:\/\/isohar.com\/wp-content\/uploads\/2024\/05\/WhatsApp-Image-2024-05-24-at-11.38.24.jpeg 1200w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/>\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"pg-fabric-content\">\n\t\t\t\t\t\t\t\t<div class=\"pg-fabric-inner-content\">\n\t\t\t\t\t<h3 class=\"pg-fabric-title\">Comando de valvulas<\/h3>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\n\t\t\n\t\t<div class=\"pg-fabric-item pg-item elementor-repeater-item-568ec11\">\n\t\t\t\t\t\t\t\t<div class=\"pg-fabric-image-wrap bdt-pg-img-mask\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"1024\" src=\"https:\/\/isohar.com\/wp-content\/uploads\/2024\/05\/442417153_414988217970204_4661291153409125986_n-768x1024.jpg\" class=\"pg-fabric-img\" alt=\"\" srcset=\"https:\/\/isohar.com\/wp-content\/uploads\/2024\/05\/442417153_414988217970204_4661291153409125986_n-768x1024.jpg 768w, https:\/\/isohar.com\/wp-content\/uploads\/2024\/05\/442417153_414988217970204_4661291153409125986_n-225x300.jpg 225w, https:\/\/isohar.com\/wp-content\/uploads\/2024\/05\/442417153_414988217970204_4661291153409125986_n-1152x1536.jpg 1152w, https:\/\/isohar.com\/wp-content\/uploads\/2024\/05\/442417153_414988217970204_4661291153409125986_n.jpg 1200w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/>\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"pg-fabric-content\">\n\t\t\t\t\t\t\t\t<div class=\"pg-fabric-inner-content\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\n\t\t\n\t\t<div class=\"pg-fabric-item pg-item elementor-repeater-item-030d89a\">\n\t\t\t\t\t\t\t\t<div class=\"pg-fabric-image-wrap bdt-pg-img-mask\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"1024\" src=\"https:\/\/isohar.com\/wp-content\/uploads\/2024\/05\/442408141_414988214636871_4667780316998932581_n-768x1024.jpg\" class=\"pg-fabric-img\" alt=\"\" srcset=\"https:\/\/isohar.com\/wp-content\/uploads\/2024\/05\/442408141_414988214636871_4667780316998932581_n-768x1024.jpg 768w, https:\/\/isohar.com\/wp-content\/uploads\/2024\/05\/442408141_414988214636871_4667780316998932581_n-225x300.jpg 225w, https:\/\/isohar.com\/wp-content\/uploads\/2024\/05\/442408141_414988214636871_4667780316998932581_n-1152x1536.jpg 1152w, https:\/\/isohar.com\/wp-content\/uploads\/2024\/05\/442408141_414988214636871_4667780316998932581_n.jpg 1200w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/>\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"pg-fabric-content\">\n\t\t\t\t\t\t\t\t<div class=\"pg-fabric-inner-content\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0829cc9 elementor-widget elementor-widget-spacer\" data-id=\"0829cc9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-676cdd6 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"676cdd6\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-c031f0a\" data-id=\"c031f0a\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3894999 elementor-widget elementor-widget-video\" data-id=\"3894999\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;video_type&quot;:&quot;hosted&quot;,&quot;controls&quot;:&quot;yes&quot;}\" data-widget_type=\"video.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"e-hosted-video elementor-wrapper elementor-open-inline\">\n\t\t\t\t\t<video class=\"elementor-video\" src=\"https:\/\/isohar.com\/wp-content\/uploads\/2024\/05\/0A108130-0B31-47AB-A4B8-A601A9AD85C4-2.mov\" controls=\"\" preload=\"metadata\" controlsList=\"nodownload\"><\/video>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c376469 elementor-widget elementor-widget-spacer\" data-id=\"c376469\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-079d27f elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"079d27f\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-93afaf4\" data-id=\"93afaf4\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-e198d22 elementor-widget elementor-widget-image\" data-id=\"e198d22\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"1024\" src=\"https:\/\/isohar.com\/wp-content\/uploads\/2024\/08\/Diseno-sin-titulo-2-1024x1024.jpg\" class=\"attachment-large size-large wp-image-2823\" alt=\"\" srcset=\"https:\/\/isohar.com\/wp-content\/uploads\/2024\/08\/Diseno-sin-titulo-2-1024x1024.jpg 1024w, https:\/\/isohar.com\/wp-content\/uploads\/2024\/08\/Diseno-sin-titulo-2-300x300.jpg 300w, https:\/\/isohar.com\/wp-content\/uploads\/2024\/08\/Diseno-sin-titulo-2-150x150.jpg 150w, https:\/\/isohar.com\/wp-content\/uploads\/2024\/08\/Diseno-sin-titulo-2-768x768.jpg 768w, https:\/\/isohar.com\/wp-content\/uploads\/2024\/08\/Diseno-sin-titulo-2.jpg 1080w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Nuestras Instalaciones Reparacion y Mantenimiento Torneria y Metalurgica Comando de valvulas https:\/\/isohar.com\/wp-content\/uploads\/2024\/05\/0A108130-0B31-47AB-A4B8-A601A9AD85C4-2.mov<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"class_list":["post-2589","page","type-page","status-publish","hentry"],"acf":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/isohar.com\/index.php\/wp-json\/wp\/v2\/pages\/2589"}],"collection":[{"href":"https:\/\/isohar.com\/index.php\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/isohar.com\/index.php\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/isohar.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/isohar.com\/index.php\/wp-json\/wp\/v2\/comments?post=2589"}],"version-history":[{"count":49,"href":"https:\/\/isohar.com\/index.php\/wp-json\/wp\/v2\/pages\/2589\/revisions"}],"predecessor-version":[{"id":2831,"href":"https:\/\/isohar.com\/index.php\/wp-json\/wp\/v2\/pages\/2589\/revisions\/2831"}],"wp:attachment":[{"href":"https:\/\/isohar.com\/index.php\/wp-json\/wp\/v2\/media?parent=2589"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}